{"id":12507,"date":"2022-12-19T10:31:52","date_gmt":"2022-12-19T13:31:52","guid":{"rendered":"https:\/\/pruebaalpha.org\/?page_id=12507"},"modified":"2024-06-03T12:07:24","modified_gmt":"2024-06-03T15:07:24","slug":"curso-para-padres","status":"publish","type":"page","link":"https:\/\/pruebaalpha.org\/en\/curso-para-padres\/","title":{"rendered":"Curso para Padres"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"12507\" class=\"elementor elementor-12507\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-176333b9 elementor-section-height-min-height elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-eae-slider=\"37484\" data-id=\"176333b9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42146c34\" data-eae-slider=\"31938\" data-id=\"42146c34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32fa23b elementor-widget elementor-widget-spacer\" data-id=\"32fa23b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c74d114 elementor-widget elementor-widget-text-editor\" data-id=\"c74d114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-family: AvantGarde; font-size: 55px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 800; text-align: center; color: #ffffff;\">Curso para Padres\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb3d68 elementor-widget elementor-widget-text-editor\" data-id=\"2bb3d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Invierte positivamente en el futuro de tus hijos.<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-bde7da0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"26324\" data-id=\"bde7da0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c657227\" data-eae-slider=\"72673\" data-id=\"c657227\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-978ce74 elementor-widget elementor-widget-spacer\" data-id=\"978ce74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-704e768 elementor-widget elementor-widget-text-editor\" data-id=\"704e768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>\u00bfPor qu\u00e9 realizar el Curso para Padres?<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-54b4ca5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"5633\" data-id=\"54b4ca5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1e0a76\" data-eae-slider=\"56720\" data-id=\"c1e0a76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-62bfe08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"39094\" data-id=\"62bfe08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-021a510\" data-eae-slider=\"62896\" data-id=\"021a510\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-967211a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"967211a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-open-book\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e4ddc2 elementor-widget elementor-widget-text-editor\" data-id=\"0e4ddc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Los hijos no llegan con un manual de instrucciones<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11f56bc\" data-eae-slider=\"22392\" data-id=\"11f56bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47a80d2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"47a80d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-child\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739e476 elementor-widget elementor-widget-text-editor\" data-id=\"739e476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Ning\u00fan papel que desempe\u00f1emos en la vida ser\u00e1 m\u00e1s importante que la paternidad<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e7c39 elementor-widget elementor-widget-spacer\" data-id=\"35e7c39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac7f30c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac7f30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-48da733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"23752\" data-id=\"48da733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39044ad\" data-eae-slider=\"50077\" data-id=\"39044ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73e0853 elementor-widget elementor-widget-text-editor\" data-id=\"73e0853\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Hoy en d\u00eda la vida familiar est\u00e1 bajo gran presi\u00f3n y los padres enfrentan opciones confusas acerca de\u00a0c\u00f3mo educar hijos de forma eficaz.\u00a0Descubrir que no estamos solos en los retos que\u00a0enfrentamos y conocer ideas de otros padres puede\u00a0implicar una gran diferencia.<\/h5><h5 style=\"text-align: center;\"><strong>Todos, aun las familias m\u00e1s felices, podemos\u00a0aprender c\u00f3mo mejorar.<\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-e00b1cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"12038\" data-id=\"e00b1cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd9ba5d\" data-eae-slider=\"98683\" data-id=\"cd9ba5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cf852f elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"1cf852f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_1cf852f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_1cf852f\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/Captura-de-Pantalla-2021-07-27-a-las-16.07.42.png);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Run The Parenting Children Course<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><h5><span style=\"color: #ffffff;\">Este curso es para cualquier padre de familia, padrastro, madrastra, personas que ser\u00e1n padres potencialmente o a\u00fan<strong>\u00a0\u00a0<\/strong>para personas encargadas del cuidado de ni\u00f1os entre los 0 y 10 a\u00f1os de edad.<\/span><\/h5><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-00d86d7\" data-eae-slider=\"2975\" data-id=\"00d86d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8de841 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"a8de841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_a8de841 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_a8de841\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/Captura-de-Pantalla-2021-07-27-a-las-16.07.53.png);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Run the Parenting Teenagers Course<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><h5><span style=\"color: #ffffff;\">Este curso es para cualquier padre de familia, padrastro, madrastra, personas que ser\u00e1n padres potencialmente o a\u00fan  para personas encargadas del cuidado de ni\u00f1os entre los 11 y 18 a\u00f1os de edad.\n<\/span><\/h5><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a28bd92 elementor-widget elementor-widget-spacer\" data-id=\"a28bd92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-227a073 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"227a073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-1d2cec4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"41996\" data-id=\"1d2cec4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fdb555\" data-eae-slider=\"30726\" data-id=\"9fdb555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9bbf42 elementor-widget elementor-widget-text-editor\" data-id=\"b9bbf42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>Recomendaciones acerca de \u201c<em>El Libro para padres de familia\u201d<\/em><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d374a66 elementor-widget elementor-widget-spacer\" data-id=\"d374a66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c97521b elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"c97521b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"A sensitive and practical book that provides real ideas on how to be a good parent, a role that we all strive to fulfill in the best way possible.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg\" alt=\"Bear Grylls\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Bear Grylls<\/span><span class=\"elementor-testimonial__title\">World-renowned adventurer, writer, and TV presenter based in the United Kingdom.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"The parenting book is practical and full of wise advice. I believe it will give parents a vital ingredient in the task of raising their children: confidence! It's exactly what parents need today.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/rob-parsons.jpeg\" alt=\"Rob Parsons\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Rob Parsons<\/span><span class=\"elementor-testimonial__title\">Journalist and writer<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eadb51e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"eadb51e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed2e7b elementor-widget elementor-widget-spacer\" data-id=\"2ed2e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-417a67b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"36223\" data-id=\"417a67b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3377f60\" data-eae-slider=\"36669\" data-id=\"3377f60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04ece13 elementor-widget elementor-widget-text-editor\" data-id=\"04ece13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>\u00bfQu\u00e9 puedo esperar durante el curso?<\/em><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d696a elementor-widget elementor-widget-text-editor\" data-id=\"73d696a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"color: #ff0000;\"><strong>Un ambiente fant\u00e1stico<\/strong><\/span><\/h5><p class=\"\">Un ambiente acogedor, inspirador y divertido a la vez. Los cursos se desarrollan en toda clase de lugares: casas, restaurantes, caf\u00e9s, centros comunitarios, Iglesias, guarder\u00edas, escuelas. Donde fuere que se lleve a cabo Tu curso local, encontrar\u00e1s un muy buen ambiente y una bienvenida amigable.<\/p><h5><span style=\"color: #ff0000;\"><strong>Una comida deliciosa (o un\u00a0bocadillo)<\/strong><\/span><\/h5><p class=\"\">Cada sesi\u00f3n comienza con algo para comer y beber, para poder generar un espacio relajado para poder conocer a otros padres.<\/p><h5><span style=\"color: #ff0000;\"><strong>Charlas pr\u00e1cticas<\/strong><\/span><\/h5><p class=\"\">Charlas pr\u00e1cticas\u00a0que son informativas y divertidas\u00a0a la vez, ya sea que se proyecten\u00a0desde los DVD o sean dadas\u00a0por un orador en vivo. Incluyen\u00a0im\u00e1genes en video de padres e\u00a0hijos compartiendo sus propias\u00a0experiencias, as\u00ed como entrevistas\u00a0en la v\u00eda p\u00fablica y consejos de\u00a0expertos en la educaci\u00f3n de los\u00a0hijos.<\/p><h5><span style=\"color: #ff0000;\"><strong>Grupos peque\u00f1os (en base a la\u00a0edad de su hijo mayor)<\/strong><\/span><\/h5><p class=\"\">De modo que puedas conocer a otros padres\/tutores que tengan mucho en com\u00fan contigo.<\/p><h5><span style=\"color: #ff0000;\"><strong>Tiempo para conversar<\/strong><\/span><\/h5><p class=\"\">Tiempo para conversar acerca de los retos y desaf\u00edos que enfrentas y la manera de establecer estrategias a largo plazo para tu propia familia. Sin embargo, no se requerir\u00e1 que compartas nada acerca de tu vida familiar que no quisieras exponer. Cada parte del curso es opcional, incluyendo el hecho de compartir algo o no durante las conversaciones del grupo peque\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77e0a74 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"77e0a74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d7c269 elementor-widget elementor-widget-spacer\" data-id=\"4d7c269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbdc4ff elementor-widget elementor-widget-text-editor\" data-id=\"dbdc4ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Si deseas realizar Curso para Padres ponte en contacto con nuestro\u00a0<span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/pruebaalpha.com\/equipo\/\" target=\"_blank\" rel=\"nofollow noopener\">equipo.<\/a><\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e24b7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"12e24b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/pruebaalpha.org\/en\/equipo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctate con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-decc8a1 elementor-widget elementor-widget-spacer\" data-id=\"decc8a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Curso para Padres Invierte positivamente en el futuro de tus hijos. \u00bfPor qu\u00e9 realizar el Curso para Padres? Los hijos no llegan con un manual de instrucciones Ning\u00fan papel que desempe\u00f1emos en la vida ser\u00e1 m\u00e1s importante que la paternidad Hoy en d\u00eda la vida familiar est\u00e1 bajo gran presi\u00f3n y los padres enfrentan opciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-12507","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso para Padres - Alpha LAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pruebaalpha.org\/en\/curso-para-padres\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Curso para Padres - Alpha LAC\" \/>\n<meta name=\"twitter:description\" content=\"Curso para Padres Invierte positivamente en el futuro de tus hijos. \u00bfPor qu\u00e9 realizar el Curso para Padres? Los hijos no llegan con un manual de instrucciones Ning\u00fan papel que desempe\u00f1emos en la vida ser\u00e1 m\u00e1s importante que la paternidad Hoy en d\u00eda la vida familiar est\u00e1 bajo gran presi\u00f3n y los padres enfrentan opciones [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg\" \/>\n<meta name=\"twitter:site\" content=\"@AlphaLatam\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/\",\"url\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/\",\"name\":\"Curso para Padres - Alpha LAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pruebaalpha.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bear.jpeg\",\"datePublished\":\"2022-12-19T13:31:52+00:00\",\"dateModified\":\"2024-06-03T15:07:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pruebaalpha.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bear.jpeg\",\"contentUrl\":\"https:\\\/\\\/pruebaalpha.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bear.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/curso-para-padres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pruebaalpha.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso para Padres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#website\",\"url\":\"https:\\\/\\\/pruebaalpha.org\\\/\",\"name\":\"Alpha LATAM\",\"description\":\"Alpha es una serie de sesiones interactivas donde puedes explorar libremente lo b\u00e1sico de la fe cristiana. No hay presi\u00f3n, obligaci\u00f3n ni costo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pruebaalpha.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#organization\",\"name\":\"Alpha LATAM\",\"url\":\"https:\\\/\\\/pruebaalpha.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pruebaalpha.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Alpha-Logo_Red.png\",\"contentUrl\":\"https:\\\/\\\/pruebaalpha.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Alpha-Logo_Red.png\",\"width\":2426,\"height\":2190,\"caption\":\"Alpha LATAM\"},\"image\":{\"@id\":\"https:\\\/\\\/pruebaalpha.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alphaenespanol\",\"https:\\\/\\\/x.com\\\/AlphaLatam\",\"https:\\\/\\\/www.instagram.com\\\/alphaenespanol\",\"https:\\\/\\\/www.youtube.com\\\/@AlphaenEspanol\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso para Padres - Alpha LAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pruebaalpha.org\/en\/curso-para-padres\/","twitter_card":"summary_large_image","twitter_title":"Curso para Padres - Alpha LAC","twitter_description":"Curso para Padres Invierte positivamente en el futuro de tus hijos. \u00bfPor qu\u00e9 realizar el Curso para Padres? Los hijos no llegan con un manual de instrucciones Ning\u00fan papel que desempe\u00f1emos en la vida ser\u00e1 m\u00e1s importante que la paternidad Hoy en d\u00eda la vida familiar est\u00e1 bajo gran presi\u00f3n y los padres enfrentan opciones [&hellip;]","twitter_image":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg","twitter_site":"@AlphaLatam","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/","url":"https:\/\/pruebaalpha.org\/curso-para-padres\/","name":"Curso para Padres - Alpha LAC","isPartOf":{"@id":"https:\/\/pruebaalpha.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/#primaryimage"},"image":{"@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/#primaryimage"},"thumbnailUrl":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg","datePublished":"2022-12-19T13:31:52+00:00","dateModified":"2024-06-03T15:07:24+00:00","breadcrumb":{"@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pruebaalpha.org\/curso-para-padres\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/#primaryimage","url":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg","contentUrl":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/07\/bear.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/pruebaalpha.org\/curso-para-padres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pruebaalpha.org\/"},{"@type":"ListItem","position":2,"name":"Curso para Padres"}]},{"@type":"WebSite","@id":"https:\/\/pruebaalpha.org\/#website","url":"https:\/\/pruebaalpha.org\/","name":"Alpha LATAM","description":"Alpha es una serie de sesiones interactivas donde puedes explorar libremente lo b\u00e1sico de la fe cristiana. No hay presi\u00f3n, obligaci\u00f3n ni costo.","publisher":{"@id":"https:\/\/pruebaalpha.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pruebaalpha.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pruebaalpha.org\/#organization","name":"Alpha LATAM","url":"https:\/\/pruebaalpha.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pruebaalpha.org\/#\/schema\/logo\/image\/","url":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/08\/Alpha-Logo_Red.png","contentUrl":"https:\/\/pruebaalpha.org\/wp-content\/uploads\/2021\/08\/Alpha-Logo_Red.png","width":2426,"height":2190,"caption":"Alpha LATAM"},"image":{"@id":"https:\/\/pruebaalpha.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alphaenespanol","https:\/\/x.com\/AlphaLatam","https:\/\/www.instagram.com\/alphaenespanol","https:\/\/www.youtube.com\/@AlphaenEspanol"]}]}},"_links":{"self":[{"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/pages\/12507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/comments?post=12507"}],"version-history":[{"count":7,"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/pages\/12507\/revisions"}],"predecessor-version":[{"id":29028,"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/pages\/12507\/revisions\/29028"}],"wp:attachment":[{"href":"https:\/\/pruebaalpha.org\/en\/wp-json\/wp\/v2\/media?parent=12507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}